{"id":1057,"count":1,"description":"","link":"https:\/\/edumentors.co.uk\/blog\/tag\/ks3-science-worksheets\/","name":"ks3 science worksheets","slug":"ks3-science-worksheets","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/edumentors.co.uk\/blog\/wp-json\/wp\/v2\/tags\/1057"}],"collection":[{"href":"https:\/\/edumentors.co.uk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/edumentors.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/edumentors.co.uk\/blog\/wp-json\/wp\/v2\/posts?tags=1057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}